{"id":154169,"date":"2026-07-15T16:08:17","date_gmt":"2026-07-15T19:08:17","guid":{"rendered":"https:\/\/vozdoesporte.com.br\/radio\/?p=154169"},"modified":"2026-07-15T16:08:17","modified_gmt":"2026-07-15T19:08:17","slug":"atletico-mg-x-bahia","status":"publish","type":"post","link":"https:\/\/vozdoesporte.com.br\/radio\/atletico-mg-x-bahia\/","title":{"rendered":"ATL\u00c9TICO-MG X BAHIA"},"content":{"rendered":"<p>TER 21\/07|19H30|ATL\u00c9TICO-MG X BAHIA|2|18H|22H|https:\/\/paineldj.com.br:20172\/stream|BRASILEIR\u00c3O<\/p>\n","protected":false},"excerpt":{"rendered":"<p>TER 21\/07|19H30|ATL\u00c9TICO-MG X BAHIA|2|18H|22H|https:\/\/paineldj.com.br:20172\/stream|BRASILEIR\u00c3O<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"noticia":[],"class_list":["post-154169","post","type-post","status-publish","format-standard","hentry","category-blog"],"acf":[],"_links":{"self":[{"href":"https:\/\/vozdoesporte.com.br\/radio\/wp-json\/wp\/v2\/posts\/154169","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vozdoesporte.com.br\/radio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vozdoesporte.com.br\/radio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vozdoesporte.com.br\/radio\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/vozdoesporte.com.br\/radio\/wp-json\/wp\/v2\/comments?post=154169"}],"version-history":[{"count":1,"href":"https:\/\/vozdoesporte.com.br\/radio\/wp-json\/wp\/v2\/posts\/154169\/revisions"}],"predecessor-version":[{"id":154170,"href":"https:\/\/vozdoesporte.com.br\/radio\/wp-json\/wp\/v2\/posts\/154169\/revisions\/154170"}],"wp:attachment":[{"href":"https:\/\/vozdoesporte.com.br\/radio\/wp-json\/wp\/v2\/media?parent=154169"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vozdoesporte.com.br\/radio\/wp-json\/wp\/v2\/categories?post=154169"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vozdoesporte.com.br\/radio\/wp-json\/wp\/v2\/tags?post=154169"},{"taxonomy":"noticia","embeddable":true,"href":"https:\/\/vozdoesporte.com.br\/radio\/wp-json\/wp\/v2\/noticia?post=154169"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}